{"id":472,"date":"2024-05-12T20:55:23","date_gmt":"2024-05-12T18:55:23","guid":{"rendered":"https:\/\/azurementsport.fr\/?p=472"},"modified":"2024-05-12T20:55:25","modified_gmt":"2024-05-12T18:55:25","slug":"le-stade-nicois-qualifie-en-finale-de-nationale-soudain-les-arboras-se-sont-embrases","status":"publish","type":"post","link":"https:\/\/azurementsport.fr\/index.php\/2024\/05\/12\/le-stade-nicois-qualifie-en-finale-de-nationale-soudain-les-arboras-se-sont-embrases\/","title":{"rendered":"Le Stade Ni\u00e7ois qualifi\u00e9 en finale de Nationale : Soudain, les Arboras se sont embras\u00e9s\u2026"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Trois mille spectateurs ont pouss\u00e9 derri\u00e8re le Stade Ni\u00e7ois lors de la demi-finale de Nationale, hier face \u00e0 Suresnes (35-13). Une ambiance jamais vue jusqu\u2019alors. Replongez au c\u0153ur des tribunes de cette soir\u00e9e historique et festive.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chants enflamm\u00e9s, fumig\u00e8nes d\u00e9goupill\u00e9s et pichets de bi\u00e8re ruisselants, il r\u00e9gnait une <strong>ambiance de f\u00eate et d&rsquo;all\u00e9gresse<\/strong> hier aux alentours de <strong>20 heures <\/strong>au <strong>stade des Arboras<\/strong>. <strong>Trois mille spectateurs<\/strong> rassembl\u00e9s dans la <strong>joie<\/strong>, la <strong>communion <\/strong>et <strong>l\u2019ivresse <\/strong>pour c\u00e9l\u00e9brer <a href=\"https:\/\/azurementsport.fr\/index.php\/2024\/05\/12\/nationale-cap-sur-la-finale-pour-le-stade-nicois-apres-sa-victoire-face-a-suresnes\/\">une qualification historique du <strong>Stade Ni\u00e7ois Rugby<\/strong> en <strong>finale de Nationale<\/strong><\/a> (victoire face \u00e0 <strong>Suresnes <\/strong>35-13, en demi-finale).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Depuis la victoire face \u00e0 <strong>Albi<\/strong>, synonyme de qualification en <strong>demi-finale,<\/strong> le club avait appel\u00e9 \u00e0 la <strong>mobilisation g\u00e9n\u00e9rale<\/strong>. Le moins que l\u2019on puisse dire c\u2019est qu\u2019il a \u00e9t\u00e9 entendu. Depuis une semaine, les places s&rsquo;arrachaient pour assister \u00e0 cette rencontre historique. D\u00e8s 16 heures 30, les parkings aux alentours du stade \u00e9taient combles. Une file d\u2019attente jamais vue jusqu\u2019alors serpentait sur le parvis.<em> \u201cC\u2019est un match historique, <strong>trois ans que l\u2019on attendait de revivre des moments comme cela <\/strong><\/em>(demi-finale perdue 12-9 face \u00e0 Narbonne en 2021, NDLR)\u201d, d\u00e9clare Tony, supporter ni\u00e7ois.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Des supporters avaient pour l&rsquo;occasion rev\u00eatu leurs habits de lumi\u00e8re aux couleurs rouge et noire et peinturlur\u00e9 leurs joues de maquillage aux couleurs nissardes. Le <strong>stade des Arboras<\/strong> baignait dans une atmosph\u00e8re l\u00e9g\u00e8re de printemps, comme le veut la tradition des rencontres de <strong>phase finale<\/strong>. Des matchs \u00e0 la vie \u00e0 la mort o\u00f9 l\u2019on retient uniquement le gagnant.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/azurementsport.fr\/wp-content\/uploads\/2024\/05\/441329131_738789008462252_2763005444905210736_n-1024x768.jpg\" alt=\"\" class=\"wp-image-477\" style=\"width:665px;height:auto\" srcset=\"https:\/\/azurementsport.fr\/wp-content\/uploads\/2024\/05\/441329131_738789008462252_2763005444905210736_n-1024x768.jpg 1024w, https:\/\/azurementsport.fr\/wp-content\/uploads\/2024\/05\/441329131_738789008462252_2763005444905210736_n-300x225.jpg 300w, https:\/\/azurementsport.fr\/wp-content\/uploads\/2024\/05\/441329131_738789008462252_2763005444905210736_n-768x576.jpg 768w, https:\/\/azurementsport.fr\/wp-content\/uploads\/2024\/05\/441329131_738789008462252_2763005444905210736_n-1536x1152.jpg 1536w, https:\/\/azurementsport.fr\/wp-content\/uploads\/2024\/05\/441329131_738789008462252_2763005444905210736_n.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">3000 spectateurs ont rempli les tribunes du stade des Arboras, c&rsquo;\u00e9tait guichets ferm\u00e9s \u00a9 Q.B<\/figcaption><\/figure>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>La Populaire Sud en renfort<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si la <strong>musique festive<\/strong> a inond\u00e9 le parvis du stade au m\u00eame titre que les <strong>litres de bi\u00e8re ingurgit\u00e9s<\/strong> pendant l\u2019avant match, les visages des supporters se sont tendus petit \u00e0 petit que le coup d\u2019envoi approchait. Alors au moment de monter les marches de la tribune pour trouver difficilement son si\u00e8ge dans des <strong>trav\u00e9es pleines \u00e0 ras bords<\/strong>, la concentration et la tension \u00e9taient de mise pour les <strong>3000 spectateurs.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00e8s l\u2019\u00e9chauffement les hommes de <strong>Mariano Taverna<\/strong> et <strong>Alexandre Compan<\/strong> (coachs ni\u00e7ois), ont \u00e9t\u00e9 pouss\u00e9s par les <strong>chants <\/strong>et les <strong>encouragements <\/strong>du public. Un stade chauff\u00e9 et entra\u00een\u00e9 par les <strong>ultras<\/strong> de la <strong>Populaire Sud<\/strong> de l\u2019<strong>Allianz Riviera<\/strong>  venus en masse soutenir, comme face \u00e0 <strong>Albi<\/strong>, les rugbymans. Des ultras qui pour l\u2019occasion avaient amen\u00e9<strong> trois \u00e9normes drapeaux<\/strong> \u00e0 l\u2019effigie de l\u2019<strong>OGC Nice<\/strong> et s\u2019\u00e9taient amus\u00e9s \u00e0 faire lever toute leur partie de stade. Un <strong>air nostalgique<\/strong> des belles ann\u00e9es du <strong>stade du Ray<\/strong> r\u00e9gnait dans ces gradins non couverts.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"720\" style=\"aspect-ratio: 960 \/ 720;\" width=\"960\" controls src=\"https:\/\/azurementsport.fr\/wp-content\/uploads\/2024\/05\/436590790_26333015199630579_2968191661546995682_n.mp4\"><\/video><\/figure>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Un envahissement de terrain \u00e9vit\u00e9 de justesse<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sur le terrain, les joueurs <strong>Ni\u00e7ois <\/strong>ont rapidement pris la mesure de leur adversaire et n\u2019ont gu\u00e8re \u00e9t\u00e9 inqui\u00e9t\u00e9s. L\u2019occasion pour tout un stade d\u2019entonner des chants de plus en plus forts au fil que le chronom\u00e8tre avan\u00e7ait et que la <strong>qualification en finale<\/strong> approchait.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les ultras de la <strong>Populaire Sud<\/strong> continuaient de martyriser leurs <strong>m\u00e9gaphones<\/strong> au son de chants d\u2019habitude destin\u00e9s aux joueurs de foot de l\u2019<strong>OGC Nice<\/strong>. Mais peu importe, dans la victoire, <strong>tout le peuple ni\u00e7ois ne fait qu\u2019un.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au coup de sifflet final, l\u2019<strong>explosion de joie <\/strong>a \u00e9t\u00e9 d\u00e9mesur\u00e9e. <strong>Les tribunes ont trembl\u00e9<\/strong>, les joueurs sont rest\u00e9s de longues minutes voire heures \u00e0 profiter sur la pelouse avec leurs familles et les quelques privil\u00e9gi\u00e9s ayant r\u00e9ussi \u00e0 se faufiler \u00e0 travers le cordon de s\u00e9curit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Des agents mis \u00e0 mal par l\u2019envie gigantesque d\u2019envahir la pelouse pour <strong>communier \u00e0 trois mille <\/strong>sur le pr\u00e9. Malgr\u00e9 ce petit contretemps, la f\u00eate n\u2019a pas \u00e9t\u00e9 g\u00e2ch\u00e9e loin de l\u00e0. Plusieurs visages parmi les <strong>supporters<\/strong>, les <strong>dirigeants<\/strong>, les <strong>joueurs <\/strong>ou le <strong>staff <\/strong>ont \u00e9t\u00e9 inond\u00e9s par l\u2019\u00e9motion. <em>\u201cC\u2019est une \u00e9tape de plus de franchie, il y avait une grosse ambiance, c\u2019\u00e9tait \u00e9norme\u201d<\/em>, s\u2019est r\u00e9joui <strong>Mariano Taverna<\/strong>, entra\u00eeneur des avants du <strong>Stade Ni\u00e7ois<\/strong> apr\u00e8s la rencontre. <strong>Jules Solinas<\/strong>, demi de m\u00eal\u00e9e du club, avouait<em> \u201cbeaucoup de soulagement\u201d<\/em> au coup de sifflet final.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-text-align-center has-vivid-red-color has-text-color has-link-color wp-elements-9fadfbca9f7ca4798fdf6d5c8209700c is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><em><strong>\u201cC\u2019est une \u00e9tape de plus de franchie, il y avait une grosse ambiance, c\u2019\u00e9tait \u00e9norme\u201d<\/strong><\/em><\/p>\n<cite>MARIANO TAVERNA, coach des avants du Stade Ni\u00e7ois<\/cite><\/blockquote>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Des bus pris en charge par la mairie pour transporter cette fi\u00e8vre \u00e0 Chamb\u00e9ry !<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jusque tard dans la nuit, les abords du<strong> stade des Arboras<\/strong> ont donc chant\u00e9 ou se sont litt\u00e9ralement embras\u00e9s de par les <strong>fumig\u00e8nes craqu\u00e9s<\/strong>. Une soir\u00e9e unique o\u00f9 l\u2019on a renifl\u00e9 ces <strong>odeurs si singuli\u00e8res de victoire<\/strong>. D\u00e9sormais, il en reste une \u00e0 aller chercher, la plus importante. Celle qui peut faire plonger le <strong>Stade Ni\u00e7ois<\/strong> dans le grand bain du <strong>rugby professionnel fran\u00e7ais<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"fr\" dir=\"ltr\">C&#39;est le feu aux Arboras (litt\u00e9ralement) ! \ud83e\udde8\ud83d\udd25 <a href=\"https:\/\/twitter.com\/hashtag\/OGCNice?src=hash&amp;ref_src=twsrc%5Etfw\">#OGCNice<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/StadeNi%C3%A7ois?src=hash&amp;ref_src=twsrc%5Etfw\">#StadeNi\u00e7ois<\/a> <a href=\"https:\/\/t.co\/7OwGImmTH8\">pic.twitter.com\/7OwGImmTH8<\/a><\/p>&mdash; ARK \ud83e\udd85 (@ark_nissa) <a href=\"https:\/\/twitter.com\/ark_nissa\/status\/1789368775059337408?ref_src=twsrc%5Etfw\">May 11, 2024<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Pour v\u00e9hiculer cette joie et cette ambiance, le maire de la ville, <strong>Christian Estrosi <\/strong>a annonc\u00e9 prendre en charge le transport <strong>en bus<\/strong> des supporters souhaitant se rendre \u00e0 <strong>Chamb\u00e9ry<\/strong>. <strong>(samedi 18 mai \u00e0 18 heures)<\/strong>. Une belle initiative pour pousser les <strong>Rouge et Noir<\/strong> \u00e0 aller gagner cette finale face \u00e0 <strong>Narbonne <\/strong>!<\/p>\n\n\n\n<blockquote class=\"text-post-media\" data-text-post-permalink=\"https:\/\/www.threads.net\/@cestrosi\/post\/C63P2cHqCL-\" data-text-post-version=\"0\" id=\"ig-tp-C63P2cHqCL-\" style=\" background:#FFF; border-width: 1px; border-style: solid; border-color: #00000026; border-radius: 16px; max-width:540px; margin: 1px; min-width:270px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"> <a href=\"https:\/\/www.threads.net\/@cestrosi\/post\/C63P2cHqCL-\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%; font-family: -apple-system, BlinkMacSystemFont, sans-serif;\" target=\"_blank\" rel=\"noopener\"> <div style=\" padding: 40px; display: flex; flex-direction: column; align-items: center;\"><div style=\" display:block; height:32px; width:32px; padding-bottom:20px;\"> <svg aria-label=\"Threads\" height=\"32px\" role=\"img\" viewBox=\"0 0 192 192\" width=\"32px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"> <path d=\"M141.537 88.9883C140.71 88.5919 139.87 88.2104 139.019 87.8451C137.537 60.5382 122.616 44.905 97.5619 44.745C97.4484 44.7443 97.3355 44.7443 97.222 44.7443C82.2364 44.7443 69.7731 51.1409 62.102 62.7807L75.881 72.2328C81.6116 63.5383 90.6052 61.6848 97.2286 61.6848C97.3051 61.6848 97.3819 61.6848 97.4576 61.6855C105.707 61.7381 111.932 64.1366 115.961 68.814C118.893 72.2193 120.854 76.925 121.825 82.8638C114.511 81.6207 106.601 81.2385 98.145 81.7233C74.3247 83.0954 59.0111 96.9879 60.0396 116.292C60.5615 126.084 65.4397 134.508 73.775 140.011C80.8224 144.663 89.899 146.938 99.3323 146.423C111.79 145.74 121.563 140.987 128.381 132.296C133.559 125.696 136.834 117.143 138.28 106.366C144.217 109.949 148.617 114.664 151.047 120.332C155.179 129.967 155.42 145.8 142.501 158.708C131.182 170.016 117.576 174.908 97.0135 175.059C74.2042 174.89 56.9538 167.575 45.7381 153.317C35.2355 139.966 29.8077 120.682 29.6052 96C29.8077 71.3178 35.2355 52.0336 45.7381 38.6827C56.9538 24.4249 74.2039 17.11 97.0132 16.9405C119.988 17.1113 137.539 24.4614 149.184 38.788C154.894 45.8136 159.199 54.6488 162.037 64.9503L178.184 60.6422C174.744 47.9622 169.331 37.0357 161.965 27.974C147.036 9.60668 125.202 0.195148 97.0695 0H96.9569C68.8816 0.19447 47.2921 9.6418 32.7883 28.0793C19.8819 44.4864 13.2244 67.3157 13.0007 95.9325L13 96L13.0007 96.0675C13.2244 124.684 19.8819 147.514 32.7883 163.921C47.2921 182.358 68.8816 191.806 96.9569 192H97.0695C122.03 191.827 139.624 185.292 154.118 170.811C173.081 151.866 172.51 128.119 166.26 113.541C161.776 103.087 153.227 94.5962 141.537 88.9883ZM98.4405 129.507C88.0005 130.095 77.1544 125.409 76.6196 115.372C76.2232 107.93 81.9158 99.626 99.0812 98.6368C101.047 98.5234 102.976 98.468 104.871 98.468C111.106 98.468 116.939 99.0737 122.242 100.233C120.264 124.935 108.662 128.946 98.4405 129.507Z\" \/><\/svg><\/div> <div style=\" font-size: 15px; line-height: 21px; color: #999999; font-weight: 400; padding-bottom: 4px; \"> Publi\u00e9 par @cestrosi<\/div> <div style=\" font-size: 15px; line-height: 21px; color: #000000; font-weight: 600; \"> Voir dans Threads<\/div><\/div><\/a><\/blockquote>\n<script async src=\"https:\/\/www.threads.net\/embed.js\"><\/script>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\" style=\"font-size:18px\"><strong>Quentin Barbaza<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trois mille spectateurs ont pouss\u00e9 derri\u00e8re le Stade Ni\u00e7ois lors de la demi-finale de Nationale, hier face \u00e0 Suresnes (35-13).&hellip;<\/p>\n","protected":false},"author":1,"featured_media":478,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[232,18,234,239,235,17,14,241,12,240,236,216,238],"class_list":["post-472","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby","tag-chambery","tag-demi-finale","tag-jules-solinas","tag-mariano-taverna","tag-narbonne","tag-nationale","tag-nice","tag-populaire-sud","tag-rugby","tag-solinas","tag-stade-des-arboras","tag-stade-nicois-2","tag-taverna"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le Stade Ni\u00e7ois qualifi\u00e9 en finale de Nationale : Soudain, les Arboras se sont embras\u00e9s\u2026 - Azurement Sport<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/azurementsport.fr\/index.php\/2024\/05\/12\/le-stade-nicois-qualifie-en-finale-de-nationale-soudain-les-arboras-se-sont-embrases\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Stade Ni\u00e7ois qualifi\u00e9 en finale de Nationale : Soudain, les Arboras se sont embras\u00e9s\u2026 - Azurement Sport\" \/>\n<meta property=\"og:description\" content=\"Trois mille spectateurs ont pouss\u00e9 derri\u00e8re le Stade Ni\u00e7ois lors de la demi-finale de Nationale, hier face \u00e0 Suresnes (35-13).&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/azurementsport.fr\/index.php\/2024\/05\/12\/le-stade-nicois-qualifie-en-finale-de-nationale-soudain-les-arboras-se-sont-embrases\/\" \/>\n<meta property=\"og:site_name\" content=\"Azurement Sport\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-12T18:55:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-12T18:55:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/azurementsport.fr\/wp-content\/uploads\/2024\/05\/441211755_989999432800867_1404017721729853925_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Azurement Sport\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Azurement Sport\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/azurementsport.fr\/index.php\/2024\/05\/12\/le-stade-nicois-qualifie-en-finale-de-nationale-soudain-les-arboras-se-sont-embrases\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/azurementsport.fr\/index.php\/2024\/05\/12\/le-stade-nicois-qualifie-en-finale-de-nationale-soudain-les-arboras-se-sont-embrases\/\"},\"author\":{\"name\":\"Azurement Sport\",\"@id\":\"https:\/\/azurementsport.fr\/#\/schema\/person\/bde18bf25893b2da2f70aa0e69fa7081\"},\"headline\":\"Le Stade Ni\u00e7ois qualifi\u00e9 en finale de Nationale : Soudain, les Arboras se sont embras\u00e9s\u2026\",\"datePublished\":\"2024-05-12T18:55:23+00:00\",\"dateModified\":\"2024-05-12T18:55:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/azurementsport.fr\/index.php\/2024\/05\/12\/le-stade-nicois-qualifie-en-finale-de-nationale-soudain-les-arboras-se-sont-embrases\/\"},\"wordCount\":926,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/azurementsport.fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/azurementsport.fr\/index.php\/2024\/05\/12\/le-stade-nicois-qualifie-en-finale-de-nationale-soudain-les-arboras-se-sont-embrases\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/azurementsport.fr\/wp-content\/uploads\/2024\/05\/441211755_989999432800867_1404017721729853925_n.jpg\",\"keywords\":[\"Chamb\u00e9ry\",\"Demi-finale\",\"Jules Solinas\",\"Mariano Taverna\",\"Narbonne\",\"Nationale\",\"Nice\",\"Populaire Sud\",\"Rugby\",\"Solinas\",\"stade des Arboras\",\"Stade Ni\u00e7ois\",\"Taverna\"],\"articleSection\":[\"Rugby\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/azurementsport.fr\/index.php\/2024\/05\/12\/le-stade-nicois-qualifie-en-finale-de-nationale-soudain-les-arboras-se-sont-embrases\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/azurementsport.fr\/index.php\/2024\/05\/12\/le-stade-nicois-qualifie-en-finale-de-nationale-soudain-les-arboras-se-sont-embrases\/\",\"url\":\"https:\/\/azurementsport.fr\/index.php\/2024\/05\/12\/le-stade-nicois-qualifie-en-finale-de-nationale-soudain-les-arboras-se-sont-embrases\/\",\"name\":\"Le Stade Ni\u00e7ois qualifi\u00e9 en finale de Nationale : Soudain, les Arboras se sont embras\u00e9s\u2026 - Azurement Sport\",\"isPartOf\":{\"@id\":\"https:\/\/azurementsport.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/azurementsport.fr\/index.php\/2024\/05\/12\/le-stade-nicois-qualifie-en-finale-de-nationale-soudain-les-arboras-se-sont-embrases\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/azurementsport.fr\/index.php\/2024\/05\/12\/le-stade-nicois-qualifie-en-finale-de-nationale-soudain-les-arboras-se-sont-embrases\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/azurementsport.fr\/wp-content\/uploads\/2024\/05\/441211755_989999432800867_1404017721729853925_n.jpg\",\"datePublished\":\"2024-05-12T18:55:23+00:00\",\"dateModified\":\"2024-05-12T18:55:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/azurementsport.fr\/index.php\/2024\/05\/12\/le-stade-nicois-qualifie-en-finale-de-nationale-soudain-les-arboras-se-sont-embrases\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/azurementsport.fr\/index.php\/2024\/05\/12\/le-stade-nicois-qualifie-en-finale-de-nationale-soudain-les-arboras-se-sont-embrases\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/azurementsport.fr\/index.php\/2024\/05\/12\/le-stade-nicois-qualifie-en-finale-de-nationale-soudain-les-arboras-se-sont-embrases\/#primaryimage\",\"url\":\"https:\/\/azurementsport.fr\/wp-content\/uploads\/2024\/05\/441211755_989999432800867_1404017721729853925_n.jpg\",\"contentUrl\":\"https:\/\/azurementsport.fr\/wp-content\/uploads\/2024\/05\/441211755_989999432800867_1404017721729853925_n.jpg\",\"width\":2048,\"height\":1536,\"caption\":\"Les ultras de la Populaire Sud sont venus soutenir les joueurs du Stade Ni\u00e7ois Rugby \u00a9 Q.B\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/azurementsport.fr\/index.php\/2024\/05\/12\/le-stade-nicois-qualifie-en-finale-de-nationale-soudain-les-arboras-se-sont-embrases\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/azurementsport.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Stade Ni\u00e7ois qualifi\u00e9 en finale de Nationale : Soudain, les Arboras se sont embras\u00e9s\u2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/azurementsport.fr\/#website\",\"url\":\"https:\/\/azurementsport.fr\/\",\"name\":\"Azurement Sport\",\"description\":\"Toute l&#039;actualit\u00e9 sportive de la C\u00f4te d&#039;Azur\",\"publisher\":{\"@id\":\"https:\/\/azurementsport.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/azurementsport.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/azurementsport.fr\/#organization\",\"name\":\"Azurement Sport\",\"url\":\"https:\/\/azurementsport.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/azurementsport.fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/azurementsport.fr\/wp-content\/uploads\/2024\/05\/cropped-cropped-AZUREMENT_SPORT__1_-removebg-preview.png\",\"contentUrl\":\"https:\/\/azurementsport.fr\/wp-content\/uploads\/2024\/05\/cropped-cropped-AZUREMENT_SPORT__1_-removebg-preview.png\",\"width\":500,\"height\":224,\"caption\":\"Azurement Sport\"},\"image\":{\"@id\":\"https:\/\/azurementsport.fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/azurementsport.fr\/#\/schema\/person\/bde18bf25893b2da2f70aa0e69fa7081\",\"name\":\"Azurement Sport\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/azurementsport.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6ac2f8b3453d709891d9b248de3f290cee35f005edbe13d94d6fb2c1b54e4fbd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6ac2f8b3453d709891d9b248de3f290cee35f005edbe13d94d6fb2c1b54e4fbd?s=96&d=mm&r=g\",\"caption\":\"Azurement Sport\"},\"sameAs\":[\"http:\/\/azurementsport.fr\"],\"url\":\"https:\/\/azurementsport.fr\/index.php\/author\/admin3210\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Stade Ni\u00e7ois qualifi\u00e9 en finale de Nationale : Soudain, les Arboras se sont embras\u00e9s\u2026 - Azurement Sport","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/azurementsport.fr\/index.php\/2024\/05\/12\/le-stade-nicois-qualifie-en-finale-de-nationale-soudain-les-arboras-se-sont-embrases\/","og_locale":"fr_FR","og_type":"article","og_title":"Le Stade Ni\u00e7ois qualifi\u00e9 en finale de Nationale : Soudain, les Arboras se sont embras\u00e9s\u2026 - Azurement Sport","og_description":"Trois mille spectateurs ont pouss\u00e9 derri\u00e8re le Stade Ni\u00e7ois lors de la demi-finale de Nationale, hier face \u00e0 Suresnes (35-13).&hellip;","og_url":"https:\/\/azurementsport.fr\/index.php\/2024\/05\/12\/le-stade-nicois-qualifie-en-finale-de-nationale-soudain-les-arboras-se-sont-embrases\/","og_site_name":"Azurement Sport","article_published_time":"2024-05-12T18:55:23+00:00","article_modified_time":"2024-05-12T18:55:25+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/azurementsport.fr\/wp-content\/uploads\/2024\/05\/441211755_989999432800867_1404017721729853925_n.jpg","type":"image\/jpeg"}],"author":"Azurement Sport","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Azurement Sport","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/azurementsport.fr\/index.php\/2024\/05\/12\/le-stade-nicois-qualifie-en-finale-de-nationale-soudain-les-arboras-se-sont-embrases\/#article","isPartOf":{"@id":"https:\/\/azurementsport.fr\/index.php\/2024\/05\/12\/le-stade-nicois-qualifie-en-finale-de-nationale-soudain-les-arboras-se-sont-embrases\/"},"author":{"name":"Azurement Sport","@id":"https:\/\/azurementsport.fr\/#\/schema\/person\/bde18bf25893b2da2f70aa0e69fa7081"},"headline":"Le Stade Ni\u00e7ois qualifi\u00e9 en finale de Nationale : Soudain, les Arboras se sont embras\u00e9s\u2026","datePublished":"2024-05-12T18:55:23+00:00","dateModified":"2024-05-12T18:55:25+00:00","mainEntityOfPage":{"@id":"https:\/\/azurementsport.fr\/index.php\/2024\/05\/12\/le-stade-nicois-qualifie-en-finale-de-nationale-soudain-les-arboras-se-sont-embrases\/"},"wordCount":926,"commentCount":0,"publisher":{"@id":"https:\/\/azurementsport.fr\/#organization"},"image":{"@id":"https:\/\/azurementsport.fr\/index.php\/2024\/05\/12\/le-stade-nicois-qualifie-en-finale-de-nationale-soudain-les-arboras-se-sont-embrases\/#primaryimage"},"thumbnailUrl":"https:\/\/azurementsport.fr\/wp-content\/uploads\/2024\/05\/441211755_989999432800867_1404017721729853925_n.jpg","keywords":["Chamb\u00e9ry","Demi-finale","Jules Solinas","Mariano Taverna","Narbonne","Nationale","Nice","Populaire Sud","Rugby","Solinas","stade des Arboras","Stade Ni\u00e7ois","Taverna"],"articleSection":["Rugby"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/azurementsport.fr\/index.php\/2024\/05\/12\/le-stade-nicois-qualifie-en-finale-de-nationale-soudain-les-arboras-se-sont-embrases\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/azurementsport.fr\/index.php\/2024\/05\/12\/le-stade-nicois-qualifie-en-finale-de-nationale-soudain-les-arboras-se-sont-embrases\/","url":"https:\/\/azurementsport.fr\/index.php\/2024\/05\/12\/le-stade-nicois-qualifie-en-finale-de-nationale-soudain-les-arboras-se-sont-embrases\/","name":"Le Stade Ni\u00e7ois qualifi\u00e9 en finale de Nationale : Soudain, les Arboras se sont embras\u00e9s\u2026 - Azurement Sport","isPartOf":{"@id":"https:\/\/azurementsport.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/azurementsport.fr\/index.php\/2024\/05\/12\/le-stade-nicois-qualifie-en-finale-de-nationale-soudain-les-arboras-se-sont-embrases\/#primaryimage"},"image":{"@id":"https:\/\/azurementsport.fr\/index.php\/2024\/05\/12\/le-stade-nicois-qualifie-en-finale-de-nationale-soudain-les-arboras-se-sont-embrases\/#primaryimage"},"thumbnailUrl":"https:\/\/azurementsport.fr\/wp-content\/uploads\/2024\/05\/441211755_989999432800867_1404017721729853925_n.jpg","datePublished":"2024-05-12T18:55:23+00:00","dateModified":"2024-05-12T18:55:25+00:00","breadcrumb":{"@id":"https:\/\/azurementsport.fr\/index.php\/2024\/05\/12\/le-stade-nicois-qualifie-en-finale-de-nationale-soudain-les-arboras-se-sont-embrases\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/azurementsport.fr\/index.php\/2024\/05\/12\/le-stade-nicois-qualifie-en-finale-de-nationale-soudain-les-arboras-se-sont-embrases\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/azurementsport.fr\/index.php\/2024\/05\/12\/le-stade-nicois-qualifie-en-finale-de-nationale-soudain-les-arboras-se-sont-embrases\/#primaryimage","url":"https:\/\/azurementsport.fr\/wp-content\/uploads\/2024\/05\/441211755_989999432800867_1404017721729853925_n.jpg","contentUrl":"https:\/\/azurementsport.fr\/wp-content\/uploads\/2024\/05\/441211755_989999432800867_1404017721729853925_n.jpg","width":2048,"height":1536,"caption":"Les ultras de la Populaire Sud sont venus soutenir les joueurs du Stade Ni\u00e7ois Rugby \u00a9 Q.B"},{"@type":"BreadcrumbList","@id":"https:\/\/azurementsport.fr\/index.php\/2024\/05\/12\/le-stade-nicois-qualifie-en-finale-de-nationale-soudain-les-arboras-se-sont-embrases\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/azurementsport.fr\/"},{"@type":"ListItem","position":2,"name":"Le Stade Ni\u00e7ois qualifi\u00e9 en finale de Nationale : Soudain, les Arboras se sont embras\u00e9s\u2026"}]},{"@type":"WebSite","@id":"https:\/\/azurementsport.fr\/#website","url":"https:\/\/azurementsport.fr\/","name":"Azurement Sport","description":"Toute l&#039;actualit\u00e9 sportive de la C\u00f4te d&#039;Azur","publisher":{"@id":"https:\/\/azurementsport.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/azurementsport.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/azurementsport.fr\/#organization","name":"Azurement Sport","url":"https:\/\/azurementsport.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/azurementsport.fr\/#\/schema\/logo\/image\/","url":"https:\/\/azurementsport.fr\/wp-content\/uploads\/2024\/05\/cropped-cropped-AZUREMENT_SPORT__1_-removebg-preview.png","contentUrl":"https:\/\/azurementsport.fr\/wp-content\/uploads\/2024\/05\/cropped-cropped-AZUREMENT_SPORT__1_-removebg-preview.png","width":500,"height":224,"caption":"Azurement Sport"},"image":{"@id":"https:\/\/azurementsport.fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/azurementsport.fr\/#\/schema\/person\/bde18bf25893b2da2f70aa0e69fa7081","name":"Azurement Sport","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/azurementsport.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6ac2f8b3453d709891d9b248de3f290cee35f005edbe13d94d6fb2c1b54e4fbd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6ac2f8b3453d709891d9b248de3f290cee35f005edbe13d94d6fb2c1b54e4fbd?s=96&d=mm&r=g","caption":"Azurement Sport"},"sameAs":["http:\/\/azurementsport.fr"],"url":"https:\/\/azurementsport.fr\/index.php\/author\/admin3210\/"}]}},"jetpack_featured_media_url":"https:\/\/azurementsport.fr\/wp-content\/uploads\/2024\/05\/441211755_989999432800867_1404017721729853925_n.jpg","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/azurementsport.fr\/index.php\/wp-json\/wp\/v2\/posts\/472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/azurementsport.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/azurementsport.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/azurementsport.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/azurementsport.fr\/index.php\/wp-json\/wp\/v2\/comments?post=472"}],"version-history":[{"count":7,"href":"https:\/\/azurementsport.fr\/index.php\/wp-json\/wp\/v2\/posts\/472\/revisions"}],"predecessor-version":[{"id":483,"href":"https:\/\/azurementsport.fr\/index.php\/wp-json\/wp\/v2\/posts\/472\/revisions\/483"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/azurementsport.fr\/index.php\/wp-json\/wp\/v2\/media\/478"}],"wp:attachment":[{"href":"https:\/\/azurementsport.fr\/index.php\/wp-json\/wp\/v2\/media?parent=472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/azurementsport.fr\/index.php\/wp-json\/wp\/v2\/categories?post=472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/azurementsport.fr\/index.php\/wp-json\/wp\/v2\/tags?post=472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}